{"id":1139,"date":"2025-03-28T11:54:22","date_gmt":"2025-03-28T11:54:22","guid":{"rendered":"https:\/\/ofsip.lu\/?page_id=1139"},"modified":"2025-09-04T07:41:30","modified_gmt":"2025-09-04T07:41:30","slug":"cofinancement-infpc","status":"publish","type":"page","link":"https:\/\/ofsip.lu\/fr\/accompagnement-et-prestations\/cofinancement-infpc\/","title":{"rendered":"Co-financement INFPC"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1139\" class=\"elementor elementor-1139\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6a9ea9 e-flex e-con-boxed e-con e-parent\" data-id=\"d6a9ea9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-63db65d e-con-full e-flex e-con e-child\" data-id=\"63db65d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cd459a4 elementor-widget elementor-widget-heading\" data-id=\"cd459a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Co-financement INFPC<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df2bc53 elementor-widget elementor-widget-text-editor\" data-id=\"df2bc53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez comment le co-financement INFPC peut transformer votre entreprise au Luxembourg.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ec7cce elementor-absolute elementor-widget elementor-widget-button\" data-id=\"7ec7cce\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ofsip-sarl.reservio.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u00c9changez avec un expert<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-23ad6b9 e-flex e-con-boxed e-con e-parent\" data-id=\"23ad6b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bbfbc4c e-con-full e-flex e-con e-child\" data-id=\"bbfbc4c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2fdec56 e-con-full e-flex e-con e-child\" data-id=\"2fdec56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-691009f elementor-widget elementor-widget-heading\" data-id=\"691009f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comprendre le processus de co-financement INFPC pour votre entreprise<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cae30b elementor-widget elementor-widget-text-editor\" data-id=\"1cae30b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le co-financement INFPC offre un soutien financier aux entreprises pour des formations professionnelles. D\u00e9couvrez les \u00e9tapes d&rsquo;\u00e9ligibilit\u00e9 et comment postuler facilement.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec207d3 elementor-widget elementor-widget-text-editor\" data-id=\"ec207d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>\u00c9ligibilit\u00e9<\/strong><\/p><p>V\u00e9rifiez si votre entreprise peut b\u00e9n\u00e9ficier<\/p><p><strong>Application<\/strong><\/p><p>Assistance pour remplir votre dossier de demande<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5f24a55 e-con-full e-flex e-con e-child\" data-id=\"5f24a55\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2683452 elementor-widget elementor-widget-image\" data-id=\"2683452\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"337\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png\" class=\"attachment-large size-large wp-image-1987\" alt=\"\" srcset=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png 1024w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-300x126.png 300w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-768x323.png 768w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1536x647.png 1536w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-18x8.png 18w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17.png 1698w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c952da4 e-flex e-con-boxed e-con e-parent\" data-id=\"c952da4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ac89cca e-con-full e-flex e-con e-child\" data-id=\"ac89cca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t<div class=\"elementor-element elementor-element-742efa2 e-con-full e-flex e-con e-child\" data-id=\"742efa2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-af1898e elementor-widget elementor-widget-image\" data-id=\"af1898e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"960\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Co-financement.png\" class=\"attachment-full size-full wp-image-1988\" alt=\"\" srcset=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Co-financement.png 1920w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Co-financement-300x150.png 300w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Co-financement-1024x512.png 1024w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Co-financement-768x384.png 768w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Co-financement-1536x768.png 1536w, https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Co-financement-18x9.png 18w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-77eb665 e-con-full e-flex e-con e-child\" data-id=\"77eb665\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d6d6be elementor-widget elementor-widget-heading\" data-id=\"7d6d6be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Suivi post-application et accompagnement continu pour le Co-financement INFPC<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a5e417 elementor-widget elementor-widget-text-editor\" data-id=\"3a5e417\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Apr\u00e8s votre demande de co-financement, nous vous accompagnons \u00e0 chaque \u00e9tape. Notre \u00e9quipe est l\u00e0 pour vous fournir des conseils personnalis\u00e9s et assurer un suivi efficace.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c88207 e-con-full e-flex e-con e-child\" data-id=\"7c88207\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-08de869 e-con-full e-flex e-con e-child\" data-id=\"08de869\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f635910 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"f635910\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"46\" height=\"46\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/Initial-Assessment.png\" class=\"attachment-full size-full wp-image-741\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Assistance d\u00e9di\u00e9e pour chaque \u00e9tape du processus.<\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ffc6b0 elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"7ffc6b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"46\" height=\"46\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/Risk-Analysis-1.png\" class=\"attachment-full size-full wp-image-832\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Suivi r\u00e9gulier pour garantir votre satisfaction.<\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32d5b2f elementor-position-left elementor-vertical-align-middle elementor-widget elementor-widget-image-box\" data-id=\"32d5b2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"46\" height=\"46\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/team-safety-1.png\" class=\"attachment-full size-full wp-image-831\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Ressources et conseils pour maximiser vos avantages.<\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86664cb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86664cb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;mdp_selection_sticky_effect_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-23b8708\" data-id=\"23b8708\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3e35033 elementor-widget elementor-widget-heading\" data-id=\"3e35033\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Co-financement<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2f9555 elementor-widget elementor-widget-heading\" data-id=\"b2f9555\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comprendre le processus de co-financement INFPC<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e5ff7a elementor-widget elementor-widget-text-editor\" data-id=\"5e5ff7a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Le co-financement INFPC est une opportunit\u00e9 pr\u00e9cieuse pour les entreprises souhaitant optimiser leurs investissements en formation. D\u00e9couvrez les \u00e9tapes cl\u00e9s pour b\u00e9n\u00e9ficier de ce soutien financier.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-bbb477c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bbb477c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;mdp_selection_sticky_effect_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-6c767f5\" data-id=\"6c767f5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-87d788a elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"87d788a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9c08ca elementor-widget__width-auto elementor-align-justify elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-widget elementor-widget-button\" data-id=\"b9c08ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/ofsip.lu\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c6dac71\" data-id=\"c6dac71\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-07be3bf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"07be3bf\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;mdp_selection_sticky_effect_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-368ac83\" data-id=\"368ac83\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-656374a boxsh elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"656374a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><g clip-path=\"url(#clip0_2156_991)\"><path d=\"M48 16.6486V47.3143C48 47.6919 47.692 48 47.3143 48H0.685714C0.308082 48 0 47.6919 0 47.3143V16.6486C0 16.271 0.308082 15.9629 0.685714 15.9629H2.58171V44.8496C2.58171 45.0839 2.70485 45.3018 2.90361 45.4277C3.09776 45.5537 3.34864 45.5702 3.5617 45.4713C5.09094 44.7564 8.92095 44.4179 12.8695 44.6484C17.5043 44.9188 21.4245 45.8817 23.6307 47.2897C23.7443 47.3612 23.8722 47.3972 24 47.3972C24.1325 47.3972 24.2557 47.3612 24.3693 47.2897C26.5755 45.8817 30.5003 44.9187 35.1352 44.6484C39.0837 44.4178 42.909 44.7564 44.4429 45.4713C44.656 45.5702 44.9021 45.5537 45.101 45.4277C45.2999 45.3018 45.4182 45.0839 45.4182 44.8496V15.9629H47.3143C47.6919 15.9629 48 16.2709 48 16.6486ZM12.2311 22.476C11.3046 20.9159 10.8484 19.2177 10.8484 17.4044V5.27325L13.679 4.5509C16.4905 3.83335 19.5415 2.78361 22.0083 1.2434L23.9999 0L25.9915 1.2434C28.4584 2.78361 31.5093 3.83335 34.3209 4.5509L37.1515 5.27325V17.4044C37.1515 19.2176 36.6954 20.916 35.7688 22.476C33.6596 26.0275 29.3983 28.2799 25.9455 30.3674L23.9999 31.5437L22.0542 30.3674C18.6014 28.2799 14.3401 26.0276 12.2309 22.476H12.2311ZM14.179 17.4044C14.179 18.6174 14.4747 19.7315 15.0947 20.7753C16.7865 23.6239 20.9971 25.8362 23.7775 27.5173L24 27.6518L24.2225 27.5173C27.0029 25.8362 31.2135 23.6239 32.9053 20.7753C33.5252 19.7316 33.821 18.6174 33.821 17.4044V7.86056L33.4973 7.77798C30.32 6.96707 27.0183 5.81075 24.2278 4.06845L24 3.92621L23.7722 4.06845C20.9816 5.81075 17.6799 6.96717 14.5027 7.77798L14.179 7.86056V17.4043V17.4044ZM18.7051 17.7578H22.0313V21.084C22.0313 21.3983 22.2877 21.6548 22.6021 21.6548H25.398C25.7123 21.6548 25.9688 21.3983 25.9688 21.084V17.7578H29.295C29.6093 17.7578 29.8658 17.5013 29.8658 17.187V14.3911C29.8658 14.0768 29.6094 13.8203 29.295 13.8203H25.9688V10.4941C25.9688 10.1797 25.7123 9.92329 25.398 9.92329H22.6021C22.2878 9.92329 22.0313 10.1797 22.0313 10.4941V13.8203H18.7051C18.3908 13.8203 18.1343 14.0768 18.1343 14.3911V17.187C18.1343 17.5013 18.3908 17.7578 18.7051 17.7578ZM36.9481 23.1763C37.9994 21.406 38.5229 19.4623 38.5229 17.4044V13.1527C40.7906 13.2053 42.7713 13.4499 44.0453 13.8432V43.8791C42.019 43.3106 38.6103 43.0715 35.0548 43.2793C30.8436 43.5253 27.1557 44.3388 24.6857 45.5468V32.7318L26.6552 31.5411C30.3609 29.3006 34.668 27.0156 36.9481 23.1763ZM32.5573 32.8763C32.6236 33.2034 32.9077 33.4303 33.2296 33.4303C33.2722 33.4303 33.3195 33.426 33.3622 33.417C35.8383 32.9318 38.4705 32.749 41.188 32.8744C41.5715 32.8933 41.8887 32.5993 41.9076 32.2211C41.9265 31.8428 41.633 31.5224 41.2543 31.5048C38.4232 31.3736 35.682 31.5645 33.0971 32.0715C32.7278 32.1444 32.4864 32.5047 32.5573 32.8763ZM41.2827 38.7734C36.2927 38.318 31.5773 38.8847 27.2738 40.4589C26.9187 40.5886 26.734 40.9825 26.8619 41.3381C26.966 41.616 27.2264 41.7888 27.5058 41.7888C27.5863 41.7888 27.6667 41.7751 27.7425 41.7467C31.8567 40.243 36.3685 39.7019 41.1597 40.1393C41.5384 40.1744 41.8698 39.8955 41.9077 39.5187C41.9408 39.1413 41.6615 38.8081 41.2828 38.7735L41.2827 38.7734ZM41.2827 35.1279C36.2833 34.7051 31.5725 35.3031 27.2785 36.9052C26.9234 37.0378 26.7435 37.4326 26.8761 37.7877C26.9802 38.0633 27.2406 38.2337 27.52 38.2337C27.6005 38.2337 27.6809 38.22 27.7567 38.1903C31.8614 36.6591 36.3732 36.0886 41.1644 36.4944C41.5431 36.527 41.8746 36.2463 41.9077 35.8689C41.9361 35.4916 41.6567 35.1597 41.2828 35.128L41.2827 35.1279ZM36.8183 28.8733C36.8467 29.2331 37.1449 29.5073 37.5 29.5073C37.5189 29.5073 37.5331 29.5063 37.5521 29.505C38.7404 29.4154 39.9666 29.388 41.2022 29.4236C41.5857 29.4335 41.8981 29.1366 41.9076 28.7579C41.9171 28.3797 41.6188 28.0639 41.2401 28.053C39.9572 28.0161 38.6836 28.0445 37.4479 28.1378C37.0739 28.1667 36.7898 28.4957 36.8183 28.8734V28.8733ZM3.95471 43.879V13.8432C5.22867 13.4499 7.20931 13.2053 9.47706 13.1527V17.4044C9.47706 19.4623 10.0006 21.406 11.052 23.1763C13.3321 27.0156 17.6391 29.3006 21.3448 31.5411L23.3142 32.7318V45.5467C20.8449 44.3387 17.161 43.5252 12.9499 43.2793C9.38968 43.0715 5.9809 43.3106 3.95461 43.8791L3.95471 43.879ZM6.09228 28.7578C6.10178 29.1365 6.41427 29.4335 6.79768 29.4235C8.03334 29.3879 9.25959 29.4154 10.4431 29.5049C10.462 29.5062 10.481 29.5072 10.5 29.5072C10.8504 29.5072 11.1533 29.2331 11.1817 28.8732C11.2102 28.4954 10.9261 28.1664 10.5474 28.1376C9.31641 28.0443 8.04294 28.0154 6.75517 28.0528C6.37646 28.0637 6.07817 28.3795 6.09238 28.7577L6.09228 28.7578ZM6.09228 32.2211C6.10648 32.5994 6.42847 32.8934 6.80718 32.8744C9.52477 32.7489 12.1617 32.9312 14.6378 33.417C14.6805 33.426 14.7231 33.4303 14.7657 33.4303C15.0876 33.4303 15.3764 33.2035 15.4427 32.8763C15.5137 32.5047 15.2722 32.1444 14.8982 32.0715C12.318 31.5645 9.57208 31.3736 6.74567 31.5048C6.36695 31.5224 6.07337 31.8429 6.09228 32.2211ZM6.09228 35.8689C6.12549 36.2462 6.45688 36.526 6.83559 36.4944C11.6268 36.0886 16.1386 36.6591 20.2386 38.1903C20.3191 38.22 20.3995 38.2337 20.48 38.2337C20.7594 38.2337 21.0198 38.0633 21.1239 37.7877C21.2565 37.4326 21.0766 37.0379 20.7215 36.9052C16.4227 35.3031 11.7167 34.7051 6.71726 35.1279C6.33845 35.1597 6.05917 35.4917 6.09228 35.8689ZM20.2575 41.7467C20.3332 41.7751 20.4137 41.7888 20.4894 41.7888C20.7688 41.7888 21.0339 41.616 21.1333 41.3381C21.2659 40.9825 21.0812 40.5886 20.7261 40.4589C16.4226 38.8847 11.7072 38.3175 6.71246 38.7734C6.33845 38.808 6.05917 39.1412 6.09228 39.5186C6.13019 39.8954 6.45688 40.1738 6.84029 40.1392C11.6267 39.7018 16.1433 40.2429 20.2575 41.7466V41.7467Z\" fill=\"#EA141D\"><\/path><\/g><defs><clipPath id=\"clip0_2156_991\"><rect width=\"48\" height=\"48\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00c9tapes du processus de co-financement\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tD\u00e9couvrez comment naviguer \u00e0 travers chaque \u00e9tape.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-87d26fa\" data-id=\"87d26fa\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-81ef5cc boxsh elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"81ef5cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><g clip-path=\"url(#clip0_2156_994)\"><path d=\"M18.3286 11.8655C18.8955 9.43292 17.3829 7.00131 14.9502 6.43433C12.5174 5.86735 10.0856 7.3797 9.51871 9.81226C8.95178 12.2448 10.4643 14.6764 12.8971 15.2434C15.3299 15.8104 17.7616 14.298 18.3286 11.8655Z\" fill=\"#EA141D\"><\/path><path d=\"M26.6507 32.5372C26.5117 31.3163 25.5059 30.372 24.2785 30.3115L17.9456 29.9964C17.9975 29.6199 18.0399 29.2564 18.0755 28.9013H41.5743V47.9001H43.6853V28.9013H46.7343V26.8909H24.6179C24.3509 27.6882 23.5984 28.2648 22.7122 28.2648H15.1766C14.2809 28.2648 13.4858 27.6633 13.2419 26.8014L11.6304 21.1048C11.4842 20.5881 11.5483 20.0457 11.8105 19.5766C12.0725 19.108 12.5015 18.7692 13.0182 18.6231C13.1971 18.5726 13.3813 18.5469 13.566 18.5469C14.4611 18.5469 15.2564 19.1494 15.4999 20.0113L16.6973 24.2439H18.0411C17.8849 23.0109 17.6105 21.7381 17.2102 20.2803C16.3682 17.2839 13.9376 16.2101 12.1995 16.5396C10.4619 16.8685 9.57146 19.216 10.0329 21.2467C10.4217 24.0877 11.1662 28.1729 10.5057 31.5971C10.1796 34.3878 10.9884 34.6323 12.8264 34.761C12.897 34.7658 12.9679 34.7702 13.0395 34.7739C13.1109 34.7837 13.183 34.792 13.2564 34.7956V34.7952L21.898 35.2252L23.0976 45.7712C23.2434 47.0535 24.3306 48.0004 25.5914 48.0004C25.6863 48.0004 25.7822 47.9952 25.8787 47.9842C27.2574 47.8275 28.2482 46.5823 28.0916 45.2035L26.6507 32.5372Z\" fill=\"#EA141D\"><\/path><path d=\"M34.9399 13.6203V6.78516H33.3315V20.456H34.9399V14.6259H36.8832V25.0801H33.2812V25.8843H41.4907V25.0801H37.8884V13.6203H34.9399Z\" fill=\"#EA141D\"><\/path><path d=\"M30.7852 25.8843V25.0801H24.6533V25.7377C24.6662 25.7859 24.678 25.8346 24.6875 25.8843H30.7852Z\" fill=\"#EA141D\"><\/path><path d=\"M3.74179 7.16143C3.92957 7.63951 5.1485 7.19922 5.29044 6.83835C6.29527 4.28407 7.90142 2.05648 10.1547 0.466615C10.4159 0.282457 10.3321 0.0502496 10.0327 0.0106437C9.65735 -0.0390145 9.23998 0.0894535 8.93439 0.304974C7.04939 1.63469 5.57352 3.39283 4.51059 5.4059C4.02969 4.81945 3.42132 4.35262 2.69937 3.98049C2.31115 3.78025 0.873274 4.37052 1.44525 4.66525C2.51541 5.21692 3.29969 6.03678 3.74179 7.16143Z\" fill=\"#EA141D\"><\/path><path d=\"M15.1135 20.1205C14.8719 19.2654 13.9831 18.7687 13.128 19.0103C12.2736 19.2518 11.7762 20.141 12.0183 20.9956L13.6292 26.6919C13.825 27.3835 14.4577 27.8627 15.1771 27.8627H22.7127C23.6011 27.8627 24.321 27.1422 24.321 26.2544C24.321 25.3658 23.6011 24.6462 22.7127 24.6462L16.3934 24.6456L15.1135 20.1205Z\" fill=\"#EA141D\"><\/path><path d=\"M10.2148 28.1968C10.2148 26.5313 8.86457 25.1811 7.19911 25.1811C6.54812 25.1811 5.9468 25.3894 5.45404 25.7402L5.24877 22.5703C5.19489 21.7396 4.47756 21.1093 3.64704 21.1634C2.81572 21.2171 2.18584 21.9344 2.23952 22.7651L3.19227 37.472C3.24334 38.2661 3.90036 38.8823 4.6965 38.8823H9.41161L9.65428 41.3278C4.89855 41.5625 3.54209 43.557 3.46027 43.7247L3.37583 43.8669V44.7683C2.71901 44.979 2.24314 45.5942 2.24314 46.3212C2.24314 47.2219 2.97354 47.9519 3.87422 47.9519C4.7751 47.9519 5.5049 47.2219 5.5049 46.3212C5.5049 45.6745 5.12774 45.1174 4.5819 44.8534V44.2378C4.90599 43.8783 6.17579 42.708 9.7737 42.5339L9.99746 44.7878C9.36879 45.0142 8.91865 45.6143 8.91865 46.321C8.91865 47.2217 9.64865 47.9517 10.5493 47.9517C11.45 47.9517 12.1804 47.2217 12.1804 46.321C12.1804 45.6921 11.8242 45.1473 11.3026 44.8753L11.5351 42.5327C13.6412 42.6326 14.9528 43.0818 15.7385 43.5024C16.184 43.741 16.4631 43.9712 16.6259 44.131C16.6665 44.1708 16.7001 44.2064 16.7269 44.2366V44.8252C16.1497 45.0763 15.7458 45.6513 15.7458 46.321C15.7458 47.2217 16.4757 47.9517 17.3764 47.9517C18.2775 47.9517 19.0075 47.2217 19.0075 46.321C19.0075 45.6159 18.5594 45.0172 17.9329 44.7894V43.8666L17.8485 43.7245C17.7673 43.5568 16.4106 41.5623 11.6545 41.3276L11.8971 38.8821H16.5576C17.3899 38.8821 18.0652 38.2068 18.0652 37.3745C18.0652 36.5416 17.3899 35.8669 16.5576 35.8669L6.10884 35.8664L5.78455 30.8598C6.20635 31.0842 6.68705 31.2122 7.1981 31.2122C8.86457 31.2124 10.2148 29.8624 10.2148 28.1968Z\" fill=\"#EA141D\"><\/path><\/g><defs><clipPath id=\"clip0_2156_994\"><rect width=\"48\" height=\"48\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\t\u00c9ligibilit\u00e9 au co-financement INFPC\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAssurez-vous que votre entreprise remplit les crit\u00e8res requis.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-19859d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19859d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;mdp_selection_sticky_effect_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8cb02ce\" data-id=\"8cb02ce\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6fac3d boxsh elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f6fac3d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><g clip-path=\"url(#clip0_2156_994)\"><path d=\"M18.3286 11.8655C18.8955 9.43292 17.3829 7.00131 14.9502 6.43433C12.5174 5.86735 10.0856 7.3797 9.51871 9.81226C8.95178 12.2448 10.4643 14.6764 12.8971 15.2434C15.3299 15.8104 17.7616 14.298 18.3286 11.8655Z\" fill=\"#EA141D\"><\/path><path d=\"M26.6507 32.5372C26.5117 31.3163 25.5059 30.372 24.2785 30.3115L17.9456 29.9964C17.9975 29.6199 18.0399 29.2564 18.0755 28.9013H41.5743V47.9001H43.6853V28.9013H46.7343V26.8909H24.6179C24.3509 27.6882 23.5984 28.2648 22.7122 28.2648H15.1766C14.2809 28.2648 13.4858 27.6633 13.2419 26.8014L11.6304 21.1048C11.4842 20.5881 11.5483 20.0457 11.8105 19.5766C12.0725 19.108 12.5015 18.7692 13.0182 18.6231C13.1971 18.5726 13.3813 18.5469 13.566 18.5469C14.4611 18.5469 15.2564 19.1494 15.4999 20.0113L16.6973 24.2439H18.0411C17.8849 23.0109 17.6105 21.7381 17.2102 20.2803C16.3682 17.2839 13.9376 16.2101 12.1995 16.5396C10.4619 16.8685 9.57146 19.216 10.0329 21.2467C10.4217 24.0877 11.1662 28.1729 10.5057 31.5971C10.1796 34.3878 10.9884 34.6323 12.8264 34.761C12.897 34.7658 12.9679 34.7702 13.0395 34.7739C13.1109 34.7837 13.183 34.792 13.2564 34.7956V34.7952L21.898 35.2252L23.0976 45.7712C23.2434 47.0535 24.3306 48.0004 25.5914 48.0004C25.6863 48.0004 25.7822 47.9952 25.8787 47.9842C27.2574 47.8275 28.2482 46.5823 28.0916 45.2035L26.6507 32.5372Z\" fill=\"#EA141D\"><\/path><path d=\"M34.9399 13.6203V6.78516H33.3315V20.456H34.9399V14.6259H36.8832V25.0801H33.2812V25.8843H41.4907V25.0801H37.8884V13.6203H34.9399Z\" fill=\"#EA141D\"><\/path><path d=\"M30.7852 25.8843V25.0801H24.6533V25.7377C24.6662 25.7859 24.678 25.8346 24.6875 25.8843H30.7852Z\" fill=\"#EA141D\"><\/path><path d=\"M3.74179 7.16143C3.92957 7.63951 5.1485 7.19922 5.29044 6.83835C6.29527 4.28407 7.90142 2.05648 10.1547 0.466615C10.4159 0.282457 10.3321 0.0502496 10.0327 0.0106437C9.65735 -0.0390145 9.23998 0.0894535 8.93439 0.304974C7.04939 1.63469 5.57352 3.39283 4.51059 5.4059C4.02969 4.81945 3.42132 4.35262 2.69937 3.98049C2.31115 3.78025 0.873274 4.37052 1.44525 4.66525C2.51541 5.21692 3.29969 6.03678 3.74179 7.16143Z\" fill=\"#EA141D\"><\/path><path d=\"M15.1135 20.1205C14.8719 19.2654 13.9831 18.7687 13.128 19.0103C12.2736 19.2518 11.7762 20.141 12.0183 20.9956L13.6292 26.6919C13.825 27.3835 14.4577 27.8627 15.1771 27.8627H22.7127C23.6011 27.8627 24.321 27.1422 24.321 26.2544C24.321 25.3658 23.6011 24.6462 22.7127 24.6462L16.3934 24.6456L15.1135 20.1205Z\" fill=\"#EA141D\"><\/path><path d=\"M10.2148 28.1968C10.2148 26.5313 8.86457 25.1811 7.19911 25.1811C6.54812 25.1811 5.9468 25.3894 5.45404 25.7402L5.24877 22.5703C5.19489 21.7396 4.47756 21.1093 3.64704 21.1634C2.81572 21.2171 2.18584 21.9344 2.23952 22.7651L3.19227 37.472C3.24334 38.2661 3.90036 38.8823 4.6965 38.8823H9.41161L9.65428 41.3278C4.89855 41.5625 3.54209 43.557 3.46027 43.7247L3.37583 43.8669V44.7683C2.71901 44.979 2.24314 45.5942 2.24314 46.3212C2.24314 47.2219 2.97354 47.9519 3.87422 47.9519C4.7751 47.9519 5.5049 47.2219 5.5049 46.3212C5.5049 45.6745 5.12774 45.1174 4.5819 44.8534V44.2378C4.90599 43.8783 6.17579 42.708 9.7737 42.5339L9.99746 44.7878C9.36879 45.0142 8.91865 45.6143 8.91865 46.321C8.91865 47.2217 9.64865 47.9517 10.5493 47.9517C11.45 47.9517 12.1804 47.2217 12.1804 46.321C12.1804 45.6921 11.8242 45.1473 11.3026 44.8753L11.5351 42.5327C13.6412 42.6326 14.9528 43.0818 15.7385 43.5024C16.184 43.741 16.4631 43.9712 16.6259 44.131C16.6665 44.1708 16.7001 44.2064 16.7269 44.2366V44.8252C16.1497 45.0763 15.7458 45.6513 15.7458 46.321C15.7458 47.2217 16.4757 47.9517 17.3764 47.9517C18.2775 47.9517 19.0075 47.2217 19.0075 46.321C19.0075 45.6159 18.5594 45.0172 17.9329 44.7894V43.8666L17.8485 43.7245C17.7673 43.5568 16.4106 41.5623 11.6545 41.3276L11.8971 38.8821H16.5576C17.3899 38.8821 18.0652 38.2068 18.0652 37.3745C18.0652 36.5416 17.3899 35.8669 16.5576 35.8669L6.10884 35.8664L5.78455 30.8598C6.20635 31.0842 6.68705 31.2122 7.1981 31.2122C8.86457 31.2124 10.2148 29.8624 10.2148 28.1968Z\" fill=\"#EA141D\"><\/path><\/g><defs><clipPath id=\"clip0_2156_994\"><rect width=\"48\" height=\"48\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tSoumission de la demande\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSuivez les instructions pour soumettre votre demande.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5fba624 elementor-hidden-tablet elementor-hidden-phone\" data-id=\"5fba624\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-71b985b boxsh elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"71b985b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"48\" viewBox=\"0 0 48 48\" fill=\"none\"><g clip-path=\"url(#clip0_2156_1004)\"><path d=\"M46.1676 8.87878L16.7699 2.6574C15.5261 2.39426 14.2933 3.1967 14.0302 4.44047L13.4717 8.02967L47.3917 15.2077L47.9502 11.6185C48.2133 10.3752 47.4114 9.14199 46.1676 8.87878Z\" fill=\"#EA141D\"><\/path><path d=\"M33.8049 15.9691C33.4615 14.7325 32.1693 14.0016 30.9331 14.3444L25.3523 15.8937L12.196 13.1094L10.7491 19.9459L1.70874 22.4551C0.472649 22.798 -0.258258 24.0902 0.0845677 25.3264L5.17935 43.6856C5.52272 44.9217 6.81504 45.653 8.05113 45.3097L37.2755 37.1997C38.5116 36.8563 39.2425 35.5645 38.8997 34.3279L38.0251 31.1762L41.3027 31.8691C42.5465 32.1327 43.7793 31.3303 44.0424 30.0865L46.1161 20.2875L34.3101 17.7892L33.8049 15.9691ZM37.1799 25.3L37.9026 21.8841C38.0112 21.3726 38.5183 21.0428 39.0297 21.1508L42.4456 21.874C42.9575 21.9825 43.2874 22.4891 43.1794 23.001L42.4566 26.4169C42.3481 26.9284 41.841 27.2587 41.3295 27.1503L37.9137 26.4275C37.4013 26.3186 37.0713 25.8114 37.1799 25.3ZM2.21729 24.2872L10.3048 22.0436L29.3872 16.7481L31.4406 16.1776C31.4781 16.1674 31.5155 16.1627 31.5521 16.1627C31.7168 16.1627 31.9137 16.2707 31.9713 16.4777L32.2124 17.346L32.9678 20.0679L2.91361 28.408L1.91713 24.8183C1.8547 24.5931 1.99211 24.3496 2.21729 24.2872ZM37.067 34.8359C37.1054 34.9752 37.0651 35.0904 37.0243 35.1625C36.9839 35.2345 36.9061 35.3287 36.7668 35.367L7.54305 43.4771C7.50611 43.4872 7.46815 43.4925 7.4316 43.4925C7.26689 43.4925 7.06995 43.3839 7.01238 43.1769L4.04075 32.4683L34.0949 24.1277L35.9279 30.7323L37.067 34.8359Z\" fill=\"#EA141D\"><\/path><path d=\"M12.2655 35.5678C12.1253 35.0636 11.5989 34.7658 11.0947 34.9056L7.68174 35.853C7.17797 35.9928 6.87978 36.5196 7.02001 37.0239L7.967 40.4364C8.10723 40.9406 8.63359 41.2383 9.13783 41.0981L12.5508 40.1511C13.055 40.0113 13.3528 39.4845 13.213 38.9803L12.2655 35.5678Z\" fill=\"#EA141D\"><\/path><\/g><defs><clipPath id=\"clip0_2156_1004\"><rect width=\"48\" height=\"48\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tProcessus d'approbation\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tRecevez des mises \u00e0 jour sur l'\u00e9tat de votre demande.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ea48e4f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ea48e4f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;mdp_selection_sticky_effect_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a8fd798\" data-id=\"a8fd798\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f858ed elementor-widget elementor-widget-heading\" data-id=\"2f858ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">T\u00e9moignages clients<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f41659 elementor-widget elementor-widget-text-editor\" data-id=\"4f41659\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez comment OFSIP a transform\u00e9 notre s\u00e9curit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-1a00e4a e-flex e-con-boxed e-con e-parent\" data-id=\"1a00e4a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-44e4c2b e-con-full e-flex e-con e-child\" data-id=\"44e4c2b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-807a01b e-con-full e-flex e-con e-child\" data-id=\"807a01b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-136083a elementor-widget elementor-widget-image\" data-id=\"136083a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"76\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/bakertilly-1.png\" class=\"attachment-full size-full wp-image-703\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b36573 e-con-full e-flex e-con e-child\" data-id=\"0b36573\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c12ac1b elementor-widget elementor-widget-image\" data-id=\"c12ac1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"290\" height=\"97\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/logo-eel.png\" class=\"attachment-full size-full wp-image-702\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4adac10 e-con-full e-flex e-con e-child\" data-id=\"4adac10\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7e0a0b elementor-widget elementor-widget-image\" data-id=\"d7e0a0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"234\" height=\"117\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/logo-gradel-2.png\" class=\"attachment-full size-full wp-image-701\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9837280 e-con-full e-flex e-con e-child\" data-id=\"9837280\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f1fc377 e-con-full e-flex e-con e-child\" data-id=\"f1fc377\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b15659b e-con-full e-flex e-con e-child\" data-id=\"b15659b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0cc0829 elementor-widget elementor-widget-image\" data-id=\"0cc0829\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"61\" height=\"60\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/logo_ATCS-1.png\" class=\"attachment-full size-full wp-image-704\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e4b53e elementor-widget elementor-widget-text-editor\" data-id=\"4e4b53e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nous tenons \u00e0 exprimer notre enti\u00e8re satisfaction envers les services d&rsquo;OFSIP SARL. La qualit\u00e9 des formations propos\u00e9es est remarquable, combinant un contenu riche et parfaitement adapt\u00e9 aux besoins sp\u00e9cifiques de notre secteur. Nos \u00e9changes ont toujours \u00e9t\u00e9 professionnels et empreints de bienveillance, favorisant une collaboration fluide et efficace. J&rsquo;ai particuli\u00e8rement appr\u00e9ci\u00e9 l&rsquo;adaptabilit\u00e9 et la r\u00e9activit\u00e9 de l&rsquo;\u00e9quipe (Monsieur MANTIONE S\u00e9bastien), qui a su aligner ses prestations avec nos exigences et objectifs. OFSIP SARL se distingue par son engagement \u00e0 offrir un service d&rsquo;excellence, et je recommande leurs services sans r\u00e9serve.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5d9aca3 e-con-full e-flex e-con e-child\" data-id=\"5d9aca3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d476cf elementor-widget elementor-widget-image\" data-id=\"6d476cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"109\" height=\"50\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/stemm-1.png\" class=\"attachment-full size-full wp-image-706\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1270784 elementor-widget elementor-widget-text-editor\" data-id=\"1270784\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Nos salari\u00e9s ont \u00e9t\u00e9 ravis de participer \u00e0 la formation premie secours!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-934257d e-con-full e-flex e-con e-child\" data-id=\"934257d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-607e17c e-con-full e-flex e-con e-child\" data-id=\"607e17c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1a8986 elementor-widget elementor-widget-image\" data-id=\"c1a8986\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"50\" height=\"35\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/logo-amfie_0-1.png\" class=\"attachment-full size-full wp-image-705\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-82904a4 elementor-widget elementor-widget-text-editor\" data-id=\"82904a4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Pour renforcer la s\u00e9curit\u00e9 et la sant\u00e9 dans notre entreprise, nous recommandons vivement de faire appel \u00e0 OFSIP. Leur expertise et leurs formations sont des atouts pour cr\u00e9er un environnement de travail plus s\u00fbr et conforme aux normes. Nous les avons choisi, car ils ont des experts de terrain, comme S\u00e9bastien, et des programmes adapt\u00e9s \u00e0 chaque secteur.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a66ae9c e-con-full e-flex e-con e-child\" data-id=\"a66ae9c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-febe15b elementor-widget elementor-widget-image\" data-id=\"febe15b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"112\" height=\"50\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/oceal-logo-transp-1024x457-1.png\" class=\"attachment-full size-full wp-image-707\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-298bf14 elementor-widget elementor-widget-text-editor\" data-id=\"298bf14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Formation compl\u00e8te et enrichissante rythm\u00e9e par de la th\u00e9orie et de la mise en pratique. S\u00e9bastien est tr\u00e8s impliqu\u00e9 et transmet son savoir avec beaucoup de p\u00e9dagogie et de professionnalisme. Nous recommandons ses formations!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f533ce9 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f533ce9\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;mdp_selection_sticky_effect_enable&quot;:false}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14c730e elementor-invisible\" data-id=\"14c730e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300,&quot;mdp_selection_sticky_column_effect_enable&quot;:false}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e5a5a60 elementor-widget elementor-widget-heading\" data-id=\"e5a5a60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Galerie d'Images<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd1ac29 elementor-widget elementor-widget-text-editor\" data-id=\"bd1ac29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez nos formations pratiques en premiers secours.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-b422982 e-flex e-con-boxed e-con e-parent\" data-id=\"b422982\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1dfb85 elementor-pagination-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"b1dfb85\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:15,&quot;sizes&quot;:[]},&quot;slides_to_scroll&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;3&quot;,&quot;slides_to_scroll_tablet&quot;:&quot;3&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/20.jpg\" alt=\"20\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/23.jpg\" alt=\"23\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/1.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/2.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/6.jpg\" alt=\"\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/10.jpg\" alt=\"10\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/13.jpg\" alt=\"13\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 8\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/03\/19.jpg\" alt=\"19\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6837b5f e-flex e-con-boxed e-con e-parent\" data-id=\"6837b5f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aaf717d e-con-full e-flex e-con e-child\" data-id=\"aaf717d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-495d071 elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"495d071\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Contactez-nous pour le co-financement<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f531aa2 elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"f531aa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>D\u00e9couvrez comment OFSIP peut vous aider \u00e0 naviguer dans le processus de co-financement INFPC.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d2b856 elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0d2b856\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"#\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">En savoir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89684ee elementor-widget__width-auto elementor-mobile-align-justify elementor-widget-mobile__width-inherit elementor-align-center elementor-widget elementor-widget-button\" data-id=\"89684ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-shrink\" href=\"https:\/\/ofsip.lu\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contact<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Co-financement INFPC D\u00e9couvrez comment le co-financement INFPC peut transformer votre entreprise au Luxembourg. \u00c9changez avec un expert Comprendre le processus de co-financement INFPC pour votre entreprise Le co-financement INFPC offre un soutien financier aux entreprises pour des formations professionnelles. D\u00e9couvrez les \u00e9tapes d&rsquo;\u00e9ligibilit\u00e9 et comment postuler facilement. \u00c9ligibilit\u00e9 V\u00e9rifiez si votre entreprise peut b\u00e9n\u00e9ficier Application [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1789,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1139","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Accompagnement Co-financement INFPC | OFSIP Luxembourg<\/title>\n<meta name=\"description\" content=\"OFSIP accompagne votre entreprise au Luxembourg dans le co-financement INFPC. B\u00e9n\u00e9ficiez d\u2019aides pour vos formations Sant\u00e9 &amp; S\u00e9curit\u00e9 au Travail.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ofsip.lu\/fr\/accompagnement-et-prestations\/cofinancement-infpc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accompagnement Co-financement INFPC | OFSIP Luxembourg\" \/>\n<meta property=\"og:description\" content=\"OFSIP accompagne votre entreprise au Luxembourg dans le co-financement INFPC. B\u00e9n\u00e9ficiez d\u2019aides pour vos formations Sant\u00e9 &amp; S\u00e9curit\u00e9 au Travail.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ofsip.lu\/fr\/accompagnement-et-prestations\/cofinancement-infpc\/\" \/>\n<meta property=\"og:site_name\" content=\"OFSIP\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-04T07:41:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/\",\"url\":\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/\",\"name\":\"Accompagnement Co-financement INFPC | OFSIP Luxembourg\",\"isPartOf\":{\"@id\":\"https:\/\/ofsip.lu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png\",\"datePublished\":\"2025-03-28T11:54:22+00:00\",\"dateModified\":\"2025-09-04T07:41:30+00:00\",\"description\":\"OFSIP accompagne votre entreprise au Luxembourg dans le co-financement INFPC. B\u00e9n\u00e9ficiez d\u2019aides pour vos formations Sant\u00e9 & S\u00e9curit\u00e9 au Travail.\",\"breadcrumb\":{\"@id\":\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#primaryimage\",\"url\":\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png\",\"contentUrl\":\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ofsip.lu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Solutions sur-Mesure\",\"item\":\"https:\/\/ofsip.lu\/accompagnement-et-prestations\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Co-financement INFPC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ofsip.lu\/#website\",\"url\":\"https:\/\/ofsip.lu\/\",\"name\":\"OFSIP\",\"description\":\"S\u00e9curiser l&#039;humain, renforcer l&#039;entreprise\",\"publisher\":{\"@id\":\"https:\/\/ofsip.lu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ofsip.lu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ofsip.lu\/#organization\",\"name\":\"OFSIP\",\"url\":\"https:\/\/ofsip.lu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/ofsip.lu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Logo-OFSIP-Color-sans-detail.png\",\"contentUrl\":\"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Logo-OFSIP-Color-sans-detail.png\",\"width\":486,\"height\":460,\"caption\":\"OFSIP\"},\"image\":{\"@id\":\"https:\/\/ofsip.lu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Accompagnement Co-financement INFPC | OFSIP Luxembourg","description":"OFSIP accompagne votre entreprise au Luxembourg dans le co-financement INFPC. B\u00e9n\u00e9ficiez d\u2019aides pour vos formations Sant\u00e9 & S\u00e9curit\u00e9 au Travail.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ofsip.lu\/fr\/accompagnement-et-prestations\/cofinancement-infpc\/","og_locale":"fr_FR","og_type":"article","og_title":"Accompagnement Co-financement INFPC | OFSIP Luxembourg","og_description":"OFSIP accompagne votre entreprise au Luxembourg dans le co-financement INFPC. B\u00e9n\u00e9ficiez d\u2019aides pour vos formations Sant\u00e9 & S\u00e9curit\u00e9 au Travail.","og_url":"https:\/\/ofsip.lu\/fr\/accompagnement-et-prestations\/cofinancement-infpc\/","og_site_name":"OFSIP","article_modified_time":"2025-09-04T07:41:30+00:00","og_image":[{"url":"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/","url":"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/","name":"Accompagnement Co-financement INFPC | OFSIP Luxembourg","isPartOf":{"@id":"https:\/\/ofsip.lu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#primaryimage"},"image":{"@id":"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#primaryimage"},"thumbnailUrl":"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png","datePublished":"2025-03-28T11:54:22+00:00","dateModified":"2025-09-04T07:41:30+00:00","description":"OFSIP accompagne votre entreprise au Luxembourg dans le co-financement INFPC. B\u00e9n\u00e9ficiez d\u2019aides pour vos formations Sant\u00e9 & S\u00e9curit\u00e9 au Travail.","breadcrumb":{"@id":"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#primaryimage","url":"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png","contentUrl":"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Capture-decran-2025-07-14-a-09.52.17-1024x431.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ofsip.lu\/accompagnement-et-prestations\/cofinancement-infpc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ofsip.lu\/"},{"@type":"ListItem","position":2,"name":"Solutions sur-Mesure","item":"https:\/\/ofsip.lu\/accompagnement-et-prestations\/"},{"@type":"ListItem","position":3,"name":"Co-financement INFPC"}]},{"@type":"WebSite","@id":"https:\/\/ofsip.lu\/#website","url":"https:\/\/ofsip.lu\/","name":"OFSIP","description":"S\u00e9curiser l&#039;humain, renforcer l&#039;entreprise","publisher":{"@id":"https:\/\/ofsip.lu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ofsip.lu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/ofsip.lu\/#organization","name":"OFSIP","url":"https:\/\/ofsip.lu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ofsip.lu\/#\/schema\/logo\/image\/","url":"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Logo-OFSIP-Color-sans-detail.png","contentUrl":"https:\/\/ofsip.lu\/wp-content\/uploads\/2025\/07\/Logo-OFSIP-Color-sans-detail.png","width":486,"height":460,"caption":"OFSIP"},"image":{"@id":"https:\/\/ofsip.lu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/pages\/1139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/comments?post=1139"}],"version-history":[{"count":23,"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/pages\/1139\/revisions"}],"predecessor-version":[{"id":2751,"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/pages\/1139\/revisions\/2751"}],"up":[{"embeddable":true,"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/pages\/1789"}],"wp:attachment":[{"href":"https:\/\/ofsip.lu\/fr\/wp-json\/wp\/v2\/media?parent=1139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}